{"id":1465,"date":"2018-11-27T01:14:21","date_gmt":"2018-11-27T01:14:21","guid":{"rendered":"https:\/\/www.portotheme.com\/wordpress\/porto\/blog2\/?page_id=1465"},"modified":"2018-12-26T00:42:08","modified_gmt":"2018-12-26T00:42:08","slug":"grid-full-width","status":"publish","type":"page","link":"https:\/\/www.portotheme.com\/wordpress\/porto\/blog2\/portfolios\/grid-full-width\/","title":{"rendered":"Full Width"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row css=&#8221;.vc_custom_1543281286335{padding-top: 30px !important;padding-right: 15px !important;padding-left: 15px !important;}&#8221;][vc_column]<div class=\"porto-portfolios porto-portfoliospdcd wpb_content_element  porto-portfolio-49a15b18bd4722017b499dda5053a7db\">\r\n\t<div class=\"page-portfolios clearfix portfolios-grid wpb_custom_f766824d32289da1f974c4f6f5382936\" id=\"porto_portfolios_p3un\">\r\n\r\n\t\r\n\t\t\t<ul class=\"portfolio-filter nav sort-source sort-source-style-3\">\r\n\t\t\t<li class=\"active\" data-filter=\"*\"><a href=\"#\">Show All<\/a><\/li>\r\n\t\t\t\t\t\t\t<li data-filter=\"brand\"><a href=\"#\">Brand<\/a><\/li>\r\n\t\t\t\t\t\t\t<li data-filter=\"design\"><a href=\"#\">Design<\/a><\/li>\r\n\t\t\t\t\t\t\t<li data-filter=\"medias\"><a href=\"#\">Medias<\/a><\/li>\r\n\t\t\t\t\t\t\t<li data-filter=\"website\"><a href=\"#\">Website<\/a><\/li>\r\n\t\t\t\t\t<\/ul>\r\n\t\t\t\t\t\r\n\t\t\t<div class=\"portfolios-container portfolio-row portfolio-row-5 default\">\r\n\r\n\t\r\n\t\t<article class=\"portfolio portfolio-grid portfolio-col-5 design post-124 type-portfolio status-publish has-post-thumbnail hentry portfolio_cat-design portfolio_skills-design portfolio_skills-htmlcss portfolio_skills-javascript\">\r\n\t\t\t\t<h3 class=\"entry-title\" style=\"display: none;\">Small Slider<\/h3><span class=\"vcard\" style=\"display: none;\"><span class=\"fn\"><a href=\"https:\/\/www.portotheme.com\/wordpress\/porto\/blog2\/author\/porto_admin\/\" title=\"Posts by Joe Doe\" rel=\"author\">Joe Doe<\/a><\/span><\/span><span class=\"updated\" style=\"display:none\">2018-11-29T09:16:23+00:00<\/span>\t\t<div class=\"portfolio-item default\">\r\n\t\t\t\r\n\t\t\t<a class=\"text-decoration-none portfolio-link\" href=\"https:\/\/www.portotheme.com\/wordpress\/porto\/blog2\/portfolio\/small-slider\/\">\r\n\t\t\t\t<span class=\"thumb-info thumb-info-lighten\">\r\n\t\t\t\t\t<span class=\"thumb-info-wrapper\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" class=\"img-responsive\" src=\"https:\/\/www.portotheme.com\/wordpress\/porto\/blog2\/wp-content\/uploads\/sites\/41\/2016\/06\/project-5-367x367.jpg\" alt=\"\" width=\"367\" height=\"367\" \/>\r\n\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\r\n\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"thumb-info-title\">\r\n\r\n\t\t\t\t\t\t\t\t\t\t<span class=\"thumb-info-inner\">Small Slider<\/span>\r\n\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"thumb-info-type\">Design<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"thumb-info-action\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"thumb-info-action-icon thumb-info-action-icon-dark opacity-8\"><i class=\"fa fa-link\"><\/i><\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t<\/span>\r\n\t\t\t<\/a>\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t<\/article>\r\n\t\t<article class=\"portfolio portfolio-grid portfolio-col-5 brand post-126 type-portfolio status-publish has-post-thumbnail hentry portfolio_cat-brand portfolio_skills-backend portfolio_skills-logo\">\r\n\t\t\t\t<h3 class=\"entry-title\" style=\"display: none;\">Large Slider<\/h3><span class=\"vcard\" style=\"display: none;\"><span class=\"fn\"><a href=\"https:\/\/www.portotheme.com\/wordpress\/porto\/blog2\/author\/porto_admin\/\" title=\"Posts by Joe Doe\" rel=\"author\">Joe Doe<\/a><\/span><\/span><span class=\"updated\" style=\"display:none\">2018-11-29T09:16:40+00:00<\/span>\t\t<div class=\"portfolio-item default\">\r\n\t\t\t\r\n\t\t\t<a class=\"text-decoration-none portfolio-link\" href=\"https:\/\/www.portotheme.com\/wordpress\/porto\/blog2\/portfolio\/large-slider\/\">\r\n\t\t\t\t<span class=\"thumb-info thumb-info-lighten\">\r\n\t\t\t\t\t<span class=\"thumb-info-wrapper\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" class=\"img-responsive\" src=\"https:\/\/www.portotheme.com\/wordpress\/porto\/blog2\/wp-content\/uploads\/sites\/41\/2016\/06\/project-7-367x367.jpg\" alt=\"\" width=\"367\" height=\"367\" \/>\r\n\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\r\n\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"thumb-info-title\">\r\n\r\n\t\t\t\t\t\t\t\t\t\t<span class=\"thumb-info-inner\">Large Slider<\/span>\r\n\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"thumb-info-type\">Brand<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"thumb-info-action\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"thumb-info-action-icon thumb-info-action-icon-dark opacity-8\"><i class=\"fa fa-link\"><\/i><\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t<\/span>\r\n\t\t\t<\/a>\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t<\/article>\r\n\t\t<article class=\"portfolio portfolio-grid portfolio-col-5 website post-120 type-portfolio status-publish has-post-thumbnail hentry portfolio_cat-website portfolio_skills-design portfolio_skills-htmlcss portfolio_skills-javascript\">\r\n\t\t\t\t<h3 class=\"entry-title\" style=\"display: none;\">Wide Slider<\/h3><span class=\"vcard\" style=\"display: none;\"><span class=\"fn\"><a href=\"https:\/\/www.portotheme.com\/wordpress\/porto\/blog2\/author\/porto_admin\/\" title=\"Posts by Joe Doe\" rel=\"author\">Joe Doe<\/a><\/span><\/span><span class=\"updated\" style=\"display:none\">2018-11-29T09:16:57+00:00<\/span>\t\t<div class=\"portfolio-item default\">\r\n\t\t\t\r\n\t\t\t<a class=\"text-decoration-none portfolio-link\" href=\"https:\/\/www.portotheme.com\/wordpress\/porto\/blog2\/portfolio\/wide-slider\/\">\r\n\t\t\t\t<span class=\"thumb-info thumb-info-lighten\">\r\n\t\t\t\t\t<span class=\"thumb-info-wrapper\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" class=\"img-responsive\" src=\"https:\/\/www.portotheme.com\/wordpress\/porto\/blog2\/wp-content\/uploads\/sites\/41\/2016\/06\/project-short-367x367.jpg\" alt=\"\" width=\"367\" height=\"367\" \/>\r\n\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\r\n\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"thumb-info-title\">\r\n\r\n\t\t\t\t\t\t\t\t\t\t<span class=\"thumb-info-inner\">Wide Slider<\/span>\r\n\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"thumb-info-type\">Website<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"thumb-info-action\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"thumb-info-action-icon thumb-info-action-icon-dark opacity-8\"><i class=\"fa fa-link\"><\/i><\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t<\/span>\r\n\t\t\t<\/a>\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t<\/article>\r\n\t\t<article class=\"portfolio portfolio-grid portfolio-col-5 medias post-129 type-portfolio status-publish has-post-thumbnail hentry portfolio_cat-medias\">\r\n\t\t\t\t<h3 class=\"entry-title\" style=\"display: none;\">Video<\/h3><span class=\"vcard\" style=\"display: none;\"><span class=\"fn\"><a href=\"https:\/\/www.portotheme.com\/wordpress\/porto\/blog2\/author\/porto_admin\/\" title=\"Posts by Joe Doe\" rel=\"author\">Joe Doe<\/a><\/span><\/span><span class=\"updated\" style=\"display:none\">2018-11-29T09:17:12+00:00<\/span>\t\t<div class=\"portfolio-item default\">\r\n\t\t\t\r\n\t\t\t<a class=\"text-decoration-none portfolio-link\" href=\"https:\/\/www.portotheme.com\/wordpress\/porto\/blog2\/portfolio\/video\/\">\r\n\t\t\t\t<span class=\"thumb-info thumb-info-lighten\">\r\n\t\t\t\t\t<span class=\"thumb-info-wrapper\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" class=\"img-responsive\" src=\"https:\/\/www.portotheme.com\/wordpress\/porto\/blog2\/wp-content\/uploads\/sites\/41\/2016\/06\/project-6-367x367.jpg\" alt=\"\" width=\"367\" height=\"367\" \/>\r\n\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\r\n\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"thumb-info-title\">\r\n\r\n\t\t\t\t\t\t\t\t\t\t<span class=\"thumb-info-inner\">Video<\/span>\r\n\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"thumb-info-type\">Medias<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"thumb-info-action\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"thumb-info-action-icon thumb-info-action-icon-dark opacity-8\"><i class=\"fa fa-link\"><\/i><\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t<\/span>\r\n\t\t\t<\/a>\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t<\/article>\r\n\t\t<article class=\"portfolio portfolio-grid portfolio-col-5 website post-116 type-portfolio status-publish has-post-thumbnail hentry portfolio_cat-website portfolio_skills-backend portfolio_skills-htmlcss portfolio_skills-logo\">\r\n\t\t\t\t<h3 class=\"entry-title\" style=\"display: none;\">Full Width Slider<\/h3><span class=\"vcard\" style=\"display: none;\"><span class=\"fn\"><a href=\"https:\/\/www.portotheme.com\/wordpress\/porto\/blog2\/author\/porto_admin\/\" title=\"Posts by Joe Doe\" rel=\"author\">Joe Doe<\/a><\/span><\/span><span class=\"updated\" style=\"display:none\">2018-11-29T09:17:20+00:00<\/span>\t\t<div class=\"portfolio-item default\">\r\n\t\t\t\r\n\t\t\t<a class=\"text-decoration-none portfolio-link\" href=\"https:\/\/www.portotheme.com\/wordpress\/porto\/blog2\/portfolio\/full-width-slider\/\">\r\n\t\t\t\t<span class=\"thumb-info thumb-info-lighten\">\r\n\t\t\t\t\t<span class=\"thumb-info-wrapper\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" class=\"img-responsive\" src=\"https:\/\/www.portotheme.com\/wordpress\/porto\/blog2\/wp-content\/uploads\/sites\/41\/2016\/06\/project-full-width-2-367x367.jpg\" alt=\"\" width=\"367\" height=\"367\" \/>\r\n\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\r\n\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"thumb-info-title\">\r\n\r\n\t\t\t\t\t\t\t\t\t\t<span class=\"thumb-info-inner\">Full Width Slider<\/span>\r\n\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"thumb-info-type\">Website<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"thumb-info-action\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"thumb-info-action-icon thumb-info-action-icon-dark opacity-8\"><i class=\"fa fa-link\"><\/i><\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t<\/span>\r\n\t\t\t<\/a>\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t<\/article>\r\n\t\t<article class=\"portfolio portfolio-grid portfolio-col-5 brand post-114 type-portfolio status-publish has-post-thumbnail hentry portfolio_cat-brand portfolio_skills-backend portfolio_skills-htmlcss portfolio_skills-javascript\">\r\n\t\t\t\t<h3 class=\"entry-title\" style=\"display: none;\">Gallery<\/h3><span class=\"vcard\" style=\"display: none;\"><span class=\"fn\"><a href=\"https:\/\/www.portotheme.com\/wordpress\/porto\/blog2\/author\/porto_admin\/\" title=\"Posts by Joe Doe\" rel=\"author\">Joe Doe<\/a><\/span><\/span><span class=\"updated\" style=\"display:none\">2018-11-29T09:17:32+00:00<\/span>\t\t<div class=\"portfolio-item default\">\r\n\t\t\t\r\n\t\t\t<a class=\"text-decoration-none portfolio-link\" href=\"https:\/\/www.portotheme.com\/wordpress\/porto\/blog2\/portfolio\/gallery\/\">\r\n\t\t\t\t<span class=\"thumb-info thumb-info-lighten\">\r\n\t\t\t\t\t<span class=\"thumb-info-wrapper\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" class=\"img-responsive\" src=\"https:\/\/www.portotheme.com\/wordpress\/porto\/blog2\/wp-content\/uploads\/sites\/41\/2016\/06\/project-1-2-367x367.jpg\" alt=\"\" width=\"367\" height=\"367\" \/>\r\n\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\r\n\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"thumb-info-title\">\r\n\r\n\t\t\t\t\t\t\t\t\t\t<span class=\"thumb-info-inner\">Gallery<\/span>\r\n\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"thumb-info-type\">Brand<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"thumb-info-action\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"thumb-info-action-icon thumb-info-action-icon-dark opacity-8\"><i class=\"fa fa-link\"><\/i><\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t<\/span>\r\n\t\t\t<\/a>\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t<\/article>\r\n\t\t<article class=\"portfolio portfolio-grid portfolio-col-5 medias post-104 type-portfolio status-publish has-post-thumbnail hentry portfolio_cat-medias portfolio_skills-backend portfolio_skills-design portfolio_skills-htmlcss portfolio_skills-javascript\">\r\n\t\t\t\t<h3 class=\"entry-title\" style=\"display: none;\">Medias<\/h3><span class=\"vcard\" style=\"display: none;\"><span class=\"fn\"><a href=\"https:\/\/www.portotheme.com\/wordpress\/porto\/blog2\/author\/porto_admin\/\" title=\"Posts by Joe Doe\" rel=\"author\">Joe Doe<\/a><\/span><\/span><span class=\"updated\" style=\"display:none\">2018-11-29T09:18:36+00:00<\/span>\t\t<div class=\"portfolio-item default\">\r\n\t\t\t\r\n\t\t\t<a class=\"text-decoration-none portfolio-link\" href=\"https:\/\/www.portotheme.com\/wordpress\/porto\/blog2\/portfolio\/medias\/\">\r\n\t\t\t\t<span class=\"thumb-info thumb-info-lighten\">\r\n\t\t\t\t\t<span class=\"thumb-info-wrapper\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" class=\"img-responsive\" src=\"https:\/\/www.portotheme.com\/wordpress\/porto\/blog2\/wp-content\/uploads\/sites\/41\/2016\/06\/project-4-367x367.jpg\" alt=\"\" width=\"367\" height=\"367\" \/>\r\n\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\r\n\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"thumb-info-title\">\r\n\r\n\t\t\t\t\t\t\t\t\t\t<span class=\"thumb-info-inner\">Medias<\/span>\r\n\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"thumb-info-type\">Medias<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"thumb-info-action\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"thumb-info-action-icon thumb-info-action-icon-dark opacity-8\"><i class=\"fa fa-link\"><\/i><\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t<\/span>\r\n\t\t\t<\/a>\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t<\/article>\r\n\t\t<article class=\"portfolio portfolio-grid portfolio-col-5 medias post-102 type-portfolio status-publish has-post-thumbnail hentry portfolio_cat-medias portfolio_skills-design portfolio_skills-htmlcss portfolio_skills-logo\">\r\n\t\t\t\t<h3 class=\"entry-title\" style=\"display: none;\">Full Width Video<\/h3><span class=\"vcard\" style=\"display: none;\"><span class=\"fn\"><a href=\"https:\/\/www.portotheme.com\/wordpress\/porto\/blog2\/author\/porto_admin\/\" title=\"Posts by Joe Doe\" rel=\"author\">Joe Doe<\/a><\/span><\/span><span class=\"updated\" style=\"display:none\">2018-11-29T09:18:52+00:00<\/span>\t\t<div class=\"portfolio-item default\">\r\n\t\t\t\r\n\t\t\t<a class=\"text-decoration-none portfolio-link\" href=\"https:\/\/www.portotheme.com\/wordpress\/porto\/blog2\/portfolio\/full-width-video\/\">\r\n\t\t\t\t<span class=\"thumb-info thumb-info-lighten\">\r\n\t\t\t\t\t<span class=\"thumb-info-wrapper\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" class=\"img-responsive\" src=\"https:\/\/www.portotheme.com\/wordpress\/porto\/blog2\/wp-content\/uploads\/sites\/41\/2016\/06\/project-3-367x367.jpg\" alt=\"\" width=\"367\" height=\"367\" \/>\r\n\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\r\n\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"thumb-info-title\">\r\n\r\n\t\t\t\t\t\t\t\t\t\t<span class=\"thumb-info-inner\">Full Width Video<\/span>\r\n\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"thumb-info-type\">Medias<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"thumb-info-action\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"thumb-info-action-icon thumb-info-action-icon-dark opacity-8\"><i class=\"fa fa-link\"><\/i><\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t<\/span>\r\n\t\t\t<\/a>\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t<\/article>\r\n\t\t<article class=\"portfolio portfolio-grid portfolio-col-5 design post-90 type-portfolio status-publish has-post-thumbnail hentry portfolio_cat-design portfolio_skills-design portfolio_skills-logo\">\r\n\t\t\t\t<h3 class=\"entry-title\" style=\"display: none;\">Masonry Images<\/h3><span class=\"vcard\" style=\"display: none;\"><span class=\"fn\"><a href=\"https:\/\/www.portotheme.com\/wordpress\/porto\/blog2\/author\/porto_admin\/\" title=\"Posts by Joe Doe\" rel=\"author\">Joe Doe<\/a><\/span><\/span><span class=\"updated\" style=\"display:none\">2018-11-29T09:19:09+00:00<\/span>\t\t<div class=\"portfolio-item default\">\r\n\t\t\t\r\n\t\t\t<a class=\"text-decoration-none portfolio-link\" href=\"https:\/\/www.portotheme.com\/wordpress\/porto\/blog2\/portfolio\/masonry-images\/\">\r\n\t\t\t\t<span class=\"thumb-info thumb-info-lighten\">\r\n\t\t\t\t\t<span class=\"thumb-info-wrapper\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" class=\"img-responsive\" src=\"https:\/\/www.portotheme.com\/wordpress\/porto\/blog2\/wp-content\/uploads\/sites\/41\/2016\/06\/project-masonry-367x367.jpg\" alt=\"\" width=\"367\" height=\"367\" \/>\r\n\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\r\n\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"thumb-info-title\">\r\n\r\n\t\t\t\t\t\t\t\t\t\t<span class=\"thumb-info-inner\">Masonry Images<\/span>\r\n\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"thumb-info-type\">Design<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"thumb-info-action\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"thumb-info-action-icon thumb-info-action-icon-dark opacity-8\"><i class=\"fa fa-link\"><\/i><\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t<\/span>\r\n\t\t\t<\/a>\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t<\/article>\r\n\t\t<article class=\"portfolio portfolio-grid portfolio-col-5 brand post-86 type-portfolio status-publish has-post-thumbnail hentry portfolio_cat-brand portfolio_skills-design portfolio_skills-logo\">\r\n\t\t\t\t<h3 class=\"entry-title\" style=\"display: none;\">Sticky Content<\/h3><span class=\"vcard\" style=\"display: none;\"><span class=\"fn\"><a href=\"https:\/\/www.portotheme.com\/wordpress\/porto\/blog2\/author\/porto_admin\/\" title=\"Posts by Joe Doe\" rel=\"author\">Joe Doe<\/a><\/span><\/span><span class=\"updated\" style=\"display:none\">2018-11-29T09:19:26+00:00<\/span>\t\t<div class=\"portfolio-item default\">\r\n\t\t\t\r\n\t\t\t<a class=\"text-decoration-none portfolio-link\" href=\"https:\/\/www.portotheme.com\/wordpress\/porto\/blog2\/portfolio\/full-images\/\">\r\n\t\t\t\t<span class=\"thumb-info thumb-info-lighten\">\r\n\t\t\t\t\t<span class=\"thumb-info-wrapper\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" class=\"img-responsive\" src=\"https:\/\/www.portotheme.com\/wordpress\/porto\/blog2\/wp-content\/uploads\/sites\/41\/2016\/06\/project-1-short-367x367.jpg\" alt=\"\" width=\"367\" height=\"367\" \/>\r\n\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\r\n\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"thumb-info-title\">\r\n\r\n\t\t\t\t\t\t\t\t\t\t<span class=\"thumb-info-inner\">Sticky Content<\/span>\r\n\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"thumb-info-type\">Brand<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"thumb-info-action\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"thumb-info-action-icon thumb-info-action-icon-dark opacity-8\"><i class=\"fa fa-link\"><\/i><\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t<\/span>\r\n\t\t\t<\/a>\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t<\/article>\r\n\t\r\n\t\r\n\t\r\n\t\t<\/div>\r\n\r\n\t\r\n\t\r\n\t<\/div>\r\n\r\n\t\r\n\t\r\n\t<\/div>[\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>[vc_row css=&#8221;.vc_custom_1543281286335{padding-top: 30px !important;padding-right: 15px !important;padding-left: 15px !important;}&#8221;][vc_column][\/vc_column][\/vc_row]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":2008,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"class_list":["post-1465","page","type-page","status-publish","hentry"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.portotheme.com\/wordpress\/porto\/blog2\/wp-json\/wp\/v2\/pages\/1465","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.portotheme.com\/wordpress\/porto\/blog2\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.portotheme.com\/wordpress\/porto\/blog2\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.portotheme.com\/wordpress\/porto\/blog2\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.portotheme.com\/wordpress\/porto\/blog2\/wp-json\/wp\/v2\/comments?post=1465"}],"version-history":[{"count":2,"href":"https:\/\/www.portotheme.com\/wordpress\/porto\/blog2\/wp-json\/wp\/v2\/pages\/1465\/revisions"}],"predecessor-version":[{"id":2056,"href":"https:\/\/www.portotheme.com\/wordpress\/porto\/blog2\/wp-json\/wp\/v2\/pages\/1465\/revisions\/2056"}],"up":[{"embeddable":true,"href":"https:\/\/www.portotheme.com\/wordpress\/porto\/blog2\/wp-json\/wp\/v2\/pages\/2008"}],"wp:attachment":[{"href":"https:\/\/www.portotheme.com\/wordpress\/porto\/blog2\/wp-json\/wp\/v2\/media?parent=1465"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}