{"id":35,"count":2,"description":"","link":"https:\/\/www.portotheme.com\/wordpress\/porto\/classic-video\/portfolio_cat\/design\/","name":"Design","slug":"design","taxonomy":"portfolio_cat","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/www.portotheme.com\/wordpress\/porto\/classic-video\/wp-json\/wp\/v2\/portfolio_cat\/35","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.portotheme.com\/wordpress\/porto\/classic-video\/wp-json\/wp\/v2\/portfolio_cat"}],"about":[{"href":"https:\/\/www.portotheme.com\/wordpress\/porto\/classic-video\/wp-json\/wp\/v2\/taxonomies\/portfolio_cat"}],"wp:post_type":[{"href":"https:\/\/www.portotheme.com\/wordpress\/porto\/classic-video\/wp-json\/wp\/v2\/portfolio?portfolio_cat=35"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}