{"id":15,"count":6,"description":"","link":"https:\/\/www.portotheme.com\/wordpress\/porto\/event\/member_cat\/member-archive\/","name":"Member Archive","slug":"member-archive","taxonomy":"member_cat","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/www.portotheme.com\/wordpress\/porto\/event\/wp-json\/wp\/v2\/member_cat\/15","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.portotheme.com\/wordpress\/porto\/event\/wp-json\/wp\/v2\/member_cat"}],"about":[{"href":"https:\/\/www.portotheme.com\/wordpress\/porto\/event\/wp-json\/wp\/v2\/taxonomies\/member_cat"}],"wp:post_type":[{"href":"https:\/\/www.portotheme.com\/wordpress\/porto\/event\/wp-json\/wp\/v2\/member?member_cat=15"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}